{"id":23233,"date":"2024-02-29T15:59:57","date_gmt":"2024-02-29T15:59:57","guid":{"rendered":"https:\/\/www.delongtop.com\/?p=23233"},"modified":"2024-05-11T02:34:29","modified_gmt":"2024-05-11T02:34:29","slug":"the-current-situation-and-future-of-sodium-ion-batteries","status":"publish","type":"post","link":"https:\/\/www.delongtop.com\/es\/the-current-situation-and-future-of-sodium-ion-batteries\/","title":{"rendered":"15 preguntas para comprender la situaci\u00f3n actual y el futuro de las bater\u00edas de iones de sodio"},"content":{"rendered":"<p>1. Los iones de sodio funcionan mejor a bajas temperaturas. 2. \u00bfPuede realmente alcanzar ahora los 160wh\/kg?<br \/>\nEn teor\u00eda se puede conseguir. Pero no se dan par\u00e1metros para la duraci\u00f3n del ciclo. La estabilidad actual de los ciclos no es buena. Los veh\u00edculos el\u00e9ctricos del mercado necesitan 2.000 ciclos, pero la investigaci\u00f3n actual s\u00f3lo permite 1.000 ciclos. 160wh\/kg. Puede cargar r\u00e1pidamente 80% de la bater\u00eda en 15 minutos, lo que te\u00f3ricamente no es ning\u00fan problema. La situaci\u00f3n de baja temperatura es mejor porque no hay composici\u00f3n y los par\u00e1metros del material, as\u00ed que desconf\u00eda. Las bater\u00edas de sodio son m\u00e1s grandes que las bater\u00edas de litio, su rendimiento din\u00e1mico es relativamente pobre, y el movimiento de los iones de sodio ser\u00e1 m\u00e1s lento. Los iones de sodio tambi\u00e9n se ven afectados por las bajas temperaturas. En general, el rendimiento a bajas temperaturas de los iones de sodio es peor que el del litio, pero no s\u00e9 si CATL ha adoptado nuevas tecnolog\u00edas.<\/p>\n<p>2. \u00bfCu\u00e1les son los principales factores que afectan a la vida \u00fatil? 3. \u00bfCu\u00e1nto margen de mejora hay en el indicador de la vida \u00fatil del ciclo y cu\u00e1ndo se puede estimar que podr\u00e1 cumplir la vida \u00fatil del ciclo de una bater\u00eda de almacenamiento de energ\u00eda? 4. Estabilidad estructural de los materiales de los electrodos positivo y negativo. El arrastre-intercalaci\u00f3n reversible de los iones de sodio hace que el material del c\u00e1todo sea un material econ\u00f3mico que puede cambiar. Algunos materiales son relativamente estables, por lo que pueden mantener la vida del ciclo. La circulaci\u00f3n de iones de sodio no es tan buena como la de otros, principalmente porque el volumen es demasiado grande, lo que provoca mayores da\u00f1os en la estructura del material. En cuanto a la vida \u00fatil, puede llegar a 1.000 veces. Pero este problema puede ser resuelto a trav\u00e9s de la tecnolog\u00eda en el futuro. Puede hacer que el material sea m\u00e1s estable. En los pr\u00f3ximos 3-5 a\u00f1os, el n\u00famero total de ciclos puede ser de 3.000-4.000 veces sin ning\u00fan problema.<\/p>\n<p>3. Si se sustituyen los materiales de los electrodos positivo y negativo, y los iones de sodio sustituyen al litio, \u00bfcu\u00e1nto disminuir\u00e1 el coste en comparaci\u00f3n con el actual?<br \/>\nEn la actualidad, los iones de sodio a\u00fan no se producen en serie. Siguen produci\u00e9ndose principalmente en laboratorios, y el coste del material es superior al del litio industrial actual.<br \/>\nSin embargo, despu\u00e9s de la producci\u00f3n en masa, todo el proceso de producci\u00f3n es igual al de las bater\u00edas de litio, y el coste total puede reducirse en unos 50%. Sin embargo, a\u00fan no se han determinado los materiales del electrodo positivo y negativo, por lo que es imposible hacer una estimaci\u00f3n. El electrodo negativo tiene una ligera ventaja sobre el litio. La mayor ventaja sigue estando en el electrodo positivo, ya que el rendimiento relativo del manganeso es m\u00e1s estable en t\u00e9rminos de iones met\u00e1licos en el electrodo positivo. Un sistema basado en \u00f3xido s\u00f3dico de manganeso y la adici\u00f3n de algunos elementos como n\u00edquel o hierro cobalto no es demasiado caro. Sin embargo, las bater\u00edas de litio son todas de alto contenido en n\u00edquel, lo que requiere no menos cobalto y n\u00edquel, y su coste es muy superior al del manganeso. Sin embargo, si se utiliza \u00f3xido de manganeso de litio, el rendimiento ser\u00e1 pobre si hay demasiado manganeso. Pero el manganeso puede utilizarse como elemento estabilizador en gran cantidad en el sodio, sin utilizar n\u00edquel ni cobalto. Utilizando manganeso como elemento met\u00e1lico principal combinado con carbonato s\u00f3dico, tras la producci\u00f3n en masa, el coste de producci\u00f3n se reducir\u00e1 significativamente en comparaci\u00f3n con las bater\u00edas de litio actuales.<\/p>\n<p>4. Si comparamos las actuales empresas nacionales de bater\u00edas de iones de litio, desde el punto de vista t\u00e9cnico, \u00bfhay alguna que est\u00e9 a la cabeza?<br \/>\nEntre las principales empresas, la de CATL cuenta con un equipo para fabricar bater\u00edas de iones de sodio. Su equipo de I+D es relativamente grande y su dise\u00f1o es m\u00e1s a largo plazo. Disponen de bater\u00edas de iones de sodio y han publicado novedades. Por lo tanto, su tecnolog\u00eda es relativamente avanzada, y muchas universidades realizan actualmente actividades de investigaci\u00f3n y desarrollo. Por ejemplo, la Academia China de Ciencias ha incubado Zhongke Haina, especializada en bater\u00edas de iones de sodio. La Universidad Jiao Tong de Shanghai incub\u00f3 Sodium Innovative Energy en Shaoxing, que produce principalmente bater\u00edas de almacenamiento de energ\u00eda y es tambi\u00e9n una empresa emergente de bater\u00edas de iones de sodio. Estas dos est\u00e1n especializadas en la investigaci\u00f3n, el desarrollo y la industria de bater\u00edas de iones de sodio, no de bater\u00edas de litio. La actividad principal de CATL es otra, salvo algunas actividades de investigaci\u00f3n y desarrollo sobre el sodio.<br \/>\nSin embargo, las bater\u00edas actuales de iones de sodio a\u00fan no est\u00e1n maduras. Aunque CATL afirm\u00f3 que se fabricar\u00e1n en serie el a\u00f1o que viene, sus productos s\u00f3lo deben estar en fase de laboratorio.<\/p>\n<p>5. Zhongke Haina ha desarrollado una bater\u00eda de sodio con una densidad energ\u00e9tica de unos 145 Wh\/kg y una vida \u00fatil de m\u00e1s de 4.500 ciclos. \u00bfQu\u00e9 te parece?<br \/>\nLa duraci\u00f3n del ciclo depende de las condiciones. En general, 2.000 ciclos est\u00e1 muy bien, pero si la carga y la descarga est\u00e1n dentro del rango de 80%, puede llegar a 3.000-4.000 veces. La duraci\u00f3n de los ciclos depende de la tensi\u00f3n de corte de carga. Si la tensi\u00f3n de corte aumenta en 0,1 voltios, su vida \u00fatil disminuir\u00e1 mucho. El material del electrodo positivo de Zhongkehaina tambi\u00e9n se basa en materiales estratificados, basados en el sistema sodio manganeso ox\u00edgeno, que est\u00e1 dopado con elementos como cobre, hierro y cobalto. El electrodo negativo tambi\u00e9n est\u00e1 hecho de carbono duro. El electrolito tambi\u00e9n debe ser hexafluorofosfato de sodio.<\/p>\n<p>6. \u00bfQu\u00e9 medidas espec\u00edficas tiene el pa\u00eds en materia de pol\u00edtica industrial?<br \/>\nEl nivel nacional es muy favorable, pero a\u00fan no hay medidas concretas. La State Grid y el Ministerio de Ciencia y Tecnolog\u00eda han presentado muchos proyectos de bater\u00edas de sodio y han invertido fondos para animar a las instituciones de investigaci\u00f3n cient\u00edfica y a las empresas a solicitarlas. La State Grid ha invertido en investigaci\u00f3n y desarrollo para aplicaciones en las que el almacenamiento de energ\u00eda es dif\u00edcil, como las estaciones de almacenamiento de energ\u00eda e\u00f3lica y solar, y la demanda de iones de sodio. Actualmente no hay otras, pero las pol\u00edticas se ir\u00e1n desplegando gradualmente.<\/p>\n<p>7. \u00bfCu\u00e1l es la diferencia entre los equipos de fabricaci\u00f3n de pilas de sodio y las pilas de litio?<br \/>\nEl equipo de fabricaci\u00f3n de materiales es casi el mismo. S\u00f3lo cambian las materias primas. Los materiales ternarios de las bater\u00edas de litio u \u00f3xido de cobalto de litio se controlan mediante electricidad de ingenier\u00eda y m\u00e9todos de fase s\u00f3lida. Las materias primas que entran en la l\u00ednea de producci\u00f3n de materiales cat\u00f3dicos son principalmente carbonato de litio, \u00f3xido de n\u00edquel, benceno \u00e1cido o sales met\u00e1licas m\u00e1s carbonato de litio o hidr\u00f3xido de litio. Las sales met\u00e1licas de las pilas de sodio no se modifican, es decir, el carbonato de litio o el hidr\u00f3xido de litio se sustituyen por carbonato de sodio e hidr\u00f3xido de sodio, pero todo el proceso de s\u00edntesis es el mismo. Los fabricantes de c\u00e1todos pueden utilizar b\u00e1sicamente los equipos actuales de producci\u00f3n de c\u00e1todos de bater\u00edas de litio, pero hay que hacer algunos ajustes en los par\u00e1metros y condiciones espec\u00edficos de producci\u00f3n. Pero el equipo es b\u00e1sicamente el mismo. La diferencia en el grafito tampoco ser\u00e1 demasiado grande. El electrolito es b\u00e1sicamente similar, es decir, el hexafluorofosfato de litio disuelto se sustituye por hexafluorofosfato de sodio, pero no difiere mucho de toda la l\u00ednea de producci\u00f3n de bater\u00edas de litio.<\/p>\n<p>8. Si se pueden utilizar iones de sodio como pilas de estado s\u00f3lido, \u00bfen cu\u00e1nto puede aumentar la densidad energ\u00e9tica? \u00bfSer\u00e1 mayor la relaci\u00f3n precio\/rendimiento?<br \/>\nLas bater\u00edas de iones de sodio en estado s\u00f3lido tienen pocas ventajas. Por un lado, su madurez tecnol\u00f3gica es actualmente relativamente baja. El principal problema es que el electrolito s\u00f3lido de las bater\u00edas de sodio no tiene un estado s\u00f3lido especialmente bueno. Por otra parte, las bater\u00edas de estado s\u00f3lido no est\u00e1n muy maduras en la actualidad, lo que tambi\u00e9n supone una barrera que las bater\u00edas de estado s\u00f3lido deben superar. O sustituir el electrolito por un electrolito s\u00f3lido. Pero los electrolitos s\u00f3lidos no han sido especialmente buenos hasta ahora. En la actualidad, los materiales para electrodos positivos y negativos m\u00e1s utilizados son materiales en capas o materiales de disco duro. Sin embargo, la relaci\u00f3n de volumen de los iones de sodio es grande y no es f\u00e1cil que migren en los s\u00f3lidos. Su conductividad i\u00f3nica es relativamente pobre en electrolitos. Por tanto, si se quiere fabricar una bater\u00eda de sodio en estado s\u00f3lido, primero hay que encontrar uno con una movilidad i\u00f3nica relativamente alta. Se tardar\u00e1 entre 5 y 10 a\u00f1os en desarrollar un producto con mejores prestaciones.<\/p>\n<p>9. Si se encuentra un buen electrolito para las pilas de sodio, \u00bfcu\u00e1nto puede aumentar la densidad energ\u00e9tica?<br \/>\nSi no puede alcanzar los 200wh\/kg, su mejora en las bater\u00edas l\u00edquidas de iones de sodio ser\u00e1 muy limitada. Si se hace bien, puede llegar a 150-180wh\/kg.<br \/>\nEl electrolito representa m\u00e1s de 20% del peso de la bater\u00eda. Si se hace todo en estado s\u00f3lido y se hace bien, se puede hacer muy fino y optimizar toda la densidad energ\u00e9tica. Sin embargo, el electrolito s\u00f3lido no puede hacerse muy fino porque existe el riesgo de cortocircuito. Si se hace grueso, se reduce la densidad energ\u00e9tica. Las bater\u00edas de sodio actuales no est\u00e1n muy maduras, por lo que el rendimiento de las bater\u00edas de estado s\u00f3lido sigue siendo muy inferior al de las bater\u00edas l\u00edquidas de iones de sodio. La capacidad de los electrodos positivo y negativo puede producir 90%-100% de la energ\u00eda en estado l\u00edquido, pero s\u00f3lo puede utilizarse 60%-70% en estado s\u00f3lido. Debido a que implica la migraci\u00f3n de iones en el s\u00f3lido, el electrolito puede penetrar en los electrodos positivo y negativo, y todas las part\u00edculas de los materiales de los electrodos positivo y negativo pueden entrar en contacto con el electrolito. Pero en un s\u00f3lido debe existir un canal de transmisi\u00f3n de iones. Sin embargo, en los electrodos positivo y negativo, es posible que las part\u00edculas no puedan tocar los electrodos positivo y negativo del electrolito. La tasa de utilizaci\u00f3n de los electrodos positivo y negativo se ver\u00e1 comprometida, y el aumento de la densidad de energ\u00eda tambi\u00e9n se ver\u00e1 reducido. ser\u00e1 limitado.<\/p>\n<p>10. \u00bfExisten planes para desarrollar bater\u00edas de iones de sodio en el extranjero? \u00bfCu\u00e1l es su progreso?<br \/>\nEstados Unidos y Europa cuentan ahora con algunos proyectos de investigaci\u00f3n, incluido Estados Unidos, que tambi\u00e9n ha puesto en marcha algunos proyectos de investigaci\u00f3n y desarrollo de bater\u00edas de iones de sodio. Sin embargo, el progreso de la investigaci\u00f3n y el desarrollo de las bater\u00edas de iones de sodio en Estados Unidos sigue estando por detr\u00e1s del de mi pa\u00eds y Corea del Sur. China y Corea del Sur van ahora por delante de Estados Unidos y Corea del Sur. Europea.<br \/>\nEn Estados Unidos hay varias empresas de nueva creaci\u00f3n que tambi\u00e9n quieren industrializar las bater\u00edas de iones de sodio, pero su escala y tecnolog\u00eda no son tan buenas como las de las empresas nacionales relacionadas. Las surcoreanas LG, Samsung y SKI tambi\u00e9n est\u00e1n haciendo planes, y sus progresos son similares a los de China.<\/p>\n<p>11. Cuando madure la tecnolog\u00eda de iones de sodio, \u00bfqu\u00e9 proporci\u00f3n representar\u00e1 en la capacidad total instalada de bater\u00edas?<br \/>\nLas ventajas t\u00e9cnicas de los iones de sodio se reflejan en los fabricantes de masa, pero la desventaja es que la densidad energ\u00e9tica es m\u00e1s d\u00e9bil que la de las bater\u00edas de iones de litio. Sus aplicaciones se centran principalmente en el almacenamiento de energ\u00eda y en herramientas el\u00e9ctricas que no requieren una alta densidad energ\u00e9tica, como los veh\u00edculos el\u00e9ctricos de baja velocidad y los autobuses el\u00e9ctricos. Por lo tanto, si la tecnolog\u00eda madura en sodio, su cuota de mercado en el campo del almacenamiento de energ\u00eda puede superar los 50%. Sin embargo, en lo que respecta a las bater\u00edas de potencia, es dif\u00edcil que las bater\u00edas de iones de sodio ocupen una cuota de mercado relativamente alta, de hasta 20%.<\/p>\n<p>12. \u00bfCu\u00e1l puede desarrollarse m\u00e1s r\u00e1pida y maduramente, las bater\u00edas de iones de sodio o las pilas de combustible?<br \/>\nDesde la perspectiva de la madurez tecnol\u00f3gica, soy m\u00e1s optimista respecto a las bater\u00edas de iones de sodio, porque el proceso es muy similar al de las bater\u00edas de iones de litio, y las bater\u00edas de iones de litio ya est\u00e1n muy maduras, por lo que el proceso de promoci\u00f3n de la producci\u00f3n en masa de bater\u00edas de iones de sodio ser\u00e1 muy r\u00e1pido, en 2-3 a\u00f1os. Pueden establecerse cadenas industriales afines.<br \/>\nSin embargo, todav\u00eda es relativamente largo el plazo para que las pilas de combustible se produzcan y apliquen en masa. Las pilas de combustible son el objetivo final para resolver los problemas energ\u00e9ticos. Lo \u00faltimo es la reacci\u00f3n del hidr\u00f3geno y el ox\u00edgeno, que es muy limpia y tiene una alta densidad energ\u00e9tica. Pero el cuello de botella actual es el almacenamiento y la liberaci\u00f3n del hidr\u00f3geno, as\u00ed como el problema de los metales preciosos en los catalizadores de las pilas de combustible. Es dif\u00edcil reducir el coste de los metales preciosos, y es dif\u00edcil encontrar tecnolog\u00edas alternativas de catalizadores finos. Por lo tanto, estos dos cuellos de botella t\u00e9cnicos son dif\u00edciles de superar a corto plazo. Pueden pasar 3\/50 a\u00f1os hasta que las pilas de combustible maduren realmente y baje el coste de la producci\u00f3n de hidr\u00f3geno.<\/p>\n<p>13. Si China puede suministrar materias primas de iones de sodio de forma totalmente independiente, \u00bfno necesita importar materiales a gran escala como los de litio?<br \/>\nComo materia prima para los iones de sodio, China dispone de suficientes recursos minerales.<\/p>\n<p>14. Coexistir\u00e1n las pilas de combustible de iones de sodio y las de iones de litio?<br \/>\nLas probabilidades son altas. Porque cada tecnolog\u00eda tiene sus caracter\u00edsticas y escenarios de aplicaci\u00f3n. Las bater\u00edas de litio, las pilas de combustible y las bater\u00edas de sodio tienen tecnolog\u00edas y escenarios de aplicaci\u00f3n diferentes, por lo que la posibilidad de coexistencia es muy alta. Incluidas las bater\u00edas de plomo-\u00e1cido no se retirar\u00e1n del mercado. La producci\u00f3n en masa y la aplicaci\u00f3n actuales de las bater\u00edas de plomo-\u00e1cido crecen cada a\u00f1o, pero el crecimiento no es tan r\u00e1pido como el de las bater\u00edas de litio.<\/p>\n<p>15. \u00bfD\u00f3nde se utiliza actualmente el plomo-\u00e1cido a gran escala?<br \/>\nCentrales de almacenamiento de energ\u00eda y bater\u00edas start-stop para veh\u00edculos de combustible, estos dos aspectos. Como su tecnolog\u00eda est\u00e1 madura, tambi\u00e9n hace un buen trabajo en el reciclaje industrial, como el de las bater\u00edas. Aunque el plomo es t\u00f3xico y contaminante, si el reciclaje se hace bien, se puede evitar la contaminaci\u00f3n. Esta tecnolog\u00eda de reciclaje es una ventaja que las bater\u00edas de litio actuales a\u00fan no tienen. Sin embargo, despu\u00e9s de que se jubile un gran n\u00famero de bater\u00edas de litio de potencia, el reciclaje de bater\u00edas tambi\u00e9n es un gran problema.<\/p>","protected":false},"excerpt":{"rendered":"<p>1. Sodium ions perform better at low temperatures. Can it really reach 160wh\/kg now? It can be achieved in theory. But no parameters  [&#8230;]<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-23233","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>15 questions to understand the current situation and future of sodium ion batteries - Delong Energy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.delongtop.com\/es\/the-current-situation-and-future-of-sodium-ion-batteries\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15 questions to understand the current situation and future of sodium ion batteries - Delong Energy\" \/>\n<meta property=\"og:description\" content=\"1. Sodium ions perform better at low temperatures. Can it really reach 160wh\/kg now? It can be achieved in theory. But no parameters [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.delongtop.com\/es\/the-current-situation-and-future-of-sodium-ion-batteries\/\" \/>\n<meta property=\"og:site_name\" content=\"Delong Energy\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-29T15:59:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-11T02:34:29+00:00\" \/>\n<meta name=\"author\" content=\"Delong\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Delong\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/\",\"url\":\"https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/\",\"name\":\"15 questions to understand the current situation and future of sodium ion batteries - Delong Energy\",\"isPartOf\":{\"@id\":\"https:\/\/www.delongtop.com\/#website\"},\"datePublished\":\"2024-02-29T15:59:57+00:00\",\"dateModified\":\"2024-05-11T02:34:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.delongtop.com\/#\/schema\/person\/a2b36b93a21fe0bafd86071ec13e827d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.delongtop.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"15 questions to understand the current situation and future of sodium ion batteries\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.delongtop.com\/#website\",\"url\":\"https:\/\/www.delongtop.com\/\",\"name\":\"Delong Energy\",\"description\":\"Lithium Ion Battery Manufacturer &amp; Factory In China\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.delongtop.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.delongtop.com\/#\/schema\/person\/a2b36b93a21fe0bafd86071ec13e827d\",\"name\":\"Delong\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.delongtop.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e82b02db42d70c5ff8bcfad9905696cdcdff156ca7fd370090f324379c648677?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e82b02db42d70c5ff8bcfad9905696cdcdff156ca7fd370090f324379c648677?s=96&d=mm&r=g\",\"caption\":\"Delong\"},\"url\":\"https:\/\/www.delongtop.com\/es\/author\/hzj\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15 questions to understand the current situation and future of sodium ion batteries - Delong Energy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.delongtop.com\/es\/the-current-situation-and-future-of-sodium-ion-batteries\/","og_locale":"es_ES","og_type":"article","og_title":"15 questions to understand the current situation and future of sodium ion batteries - Delong Energy","og_description":"1. Sodium ions perform better at low temperatures. Can it really reach 160wh\/kg now? It can be achieved in theory. But no parameters [...]","og_url":"https:\/\/www.delongtop.com\/es\/the-current-situation-and-future-of-sodium-ion-batteries\/","og_site_name":"Delong Energy","article_published_time":"2024-02-29T15:59:57+00:00","article_modified_time":"2024-05-11T02:34:29+00:00","author":"Delong","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Delong","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/","url":"https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/","name":"15 questions to understand the current situation and future of sodium ion batteries - Delong Energy","isPartOf":{"@id":"https:\/\/www.delongtop.com\/#website"},"datePublished":"2024-02-29T15:59:57+00:00","dateModified":"2024-05-11T02:34:29+00:00","author":{"@id":"https:\/\/www.delongtop.com\/#\/schema\/person\/a2b36b93a21fe0bafd86071ec13e827d"},"breadcrumb":{"@id":"https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.delongtop.com\/the-current-situation-and-future-of-sodium-ion-batteries\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.delongtop.com\/"},{"@type":"ListItem","position":2,"name":"15 questions to understand the current situation and future of sodium ion batteries"}]},{"@type":"WebSite","@id":"https:\/\/www.delongtop.com\/#website","url":"https:\/\/www.delongtop.com\/","name":"Delong Energy","description":"Lithium Ion Battery Manufacturer &amp; Factory In China","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.delongtop.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.delongtop.com\/#\/schema\/person\/a2b36b93a21fe0bafd86071ec13e827d","name":"Delong","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.delongtop.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e82b02db42d70c5ff8bcfad9905696cdcdff156ca7fd370090f324379c648677?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e82b02db42d70c5ff8bcfad9905696cdcdff156ca7fd370090f324379c648677?s=96&d=mm&r=g","caption":"Delong"},"url":"https:\/\/www.delongtop.com\/es\/author\/hzj\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.delongtop.com\/es\/wp-json\/wp\/v2\/posts\/23233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delongtop.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delongtop.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delongtop.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delongtop.com\/es\/wp-json\/wp\/v2\/comments?post=23233"}],"version-history":[{"count":0,"href":"https:\/\/www.delongtop.com\/es\/wp-json\/wp\/v2\/posts\/23233\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.delongtop.com\/es\/wp-json\/wp\/v2\/media?parent=23233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delongtop.com\/es\/wp-json\/wp\/v2\/categories?post=23233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delongtop.com\/es\/wp-json\/wp\/v2\/tags?post=23233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}