{"id":23231,"date":"2024-02-29T15:58:26","date_gmt":"2024-02-29T15:58:26","guid":{"rendered":"https:\/\/www.delongtop.com\/?p=23231"},"modified":"2024-03-02T06:12:51","modified_gmt":"2024-03-02T06:12:51","slug":"sodium-ion-batteries-open-up-new-energy-storage-tracks","status":"publish","type":"post","link":"https:\/\/www.delongtop.com\/fr\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/","title":{"rendered":"Les batteries sodium-ion ouvrent de nouvelles voies pour le stockage de l'\u00e9nergie"},"content":{"rendered":"<p>Les batteries au lithium sont omnipr\u00e9sentes dans notre travail et notre vie. Des appareils \u00e9lectroniques tels que les t\u00e9l\u00e9phones et les ordinateurs portables aux v\u00e9hicules \u00e0 \u00e9nergie nouvelle, les batteries lithium-ion sont utilis\u00e9es dans de nombreux sc\u00e9narios. Gr\u00e2ce \u00e0 leur taille r\u00e9duite, \u00e0 leurs performances plus stables et \u00e0 leur meilleure recyclabilit\u00e9, elles aident les humains \u00e0 mieux utiliser les \u00e9nergies propres.<\/p>\n<p>Ces derni\u00e8res ann\u00e9es, la Chine s'est class\u00e9e parmi les meilleurs pays du monde en ce qui concerne la recherche et le d\u00e9veloppement de technologies cl\u00e9s, la pr\u00e9paration des mat\u00e9riaux, la production de batteries et l'application des batteries sodium-ion.<\/p>\n<p><strong>Grand avantage de la r\u00e9serve<\/strong><\/p>\n<p>Actuellement, le d\u00e9veloppement du stockage \u00e9lectrochimique de l'\u00e9nergie repr\u00e9sent\u00e9 par les batteries lithium-ion s'acc\u00e9l\u00e8re. Les batteries lithium-ion ont une \u00e9nergie sp\u00e9cifique, une puissance sp\u00e9cifique, une efficacit\u00e9 de charge et de d\u00e9charge et une tension de sortie \u00e9lev\u00e9es, une longue dur\u00e9e de vie et une faible autod\u00e9charge, ce qui en fait une technologie de stockage d'\u00e9nergie id\u00e9ale. Avec la r\u00e9duction des co\u00fbts de fabrication, les batteries lithium-ion sont install\u00e9es \u00e0 grande \u00e9chelle dans le domaine du stockage \u00e9lectrochimique de l'\u00e9nergie, avec une forte dynamique de croissance.<\/p>\n<p>Selon les donn\u00e9es du minist\u00e8re de l'industrie et des technologies de l'information, la nouvelle capacit\u00e9 install\u00e9e de stockage d'\u00e9nergie en Chine augmentera de 200% d'une ann\u00e9e sur l'autre en 2022, et plus de 20 projets de 100 m\u00e9gawatts seront connect\u00e9s au r\u00e9seau. Parmi eux, le stockage d'\u00e9nergie par batterie au lithium repr\u00e9sente 97% de la capacit\u00e9 totale nouvellement install\u00e9e.<\/p>\n<p>\"La technologie de stockage de l'\u00e9nergie est un \u00e9l\u00e9ment cl\u00e9 de la pratique et de la mise en \u0153uvre de la nouvelle r\u00e9volution \u00e9nerg\u00e9tique. Dans le contexte de la strat\u00e9gie \u00e0 double objectif carbone, le stockage des nouvelles \u00e9nergies en Chine se d\u00e9veloppe rapidement\". Sun Jinhua, acad\u00e9micien de l'Acad\u00e9mie europ\u00e9enne des sciences et professeur \u00e0 l'Universit\u00e9 des sciences et technologies de Chine, a d\u00e9clar\u00e9 avec force que les nouvelles technologies de stockage de l'\u00e9nergie sont actuellement domin\u00e9es par un seul lithium.<\/p>\n<p>Parmi les nombreuses technologies de stockage d'\u00e9nergie \u00e9lectrochimique, les batteries lithium-ion ont pris une position dominante dans les appareils \u00e9lectroniques portables et les v\u00e9hicules \u00e0 \u00e9nergie nouvelle, formant une cha\u00eene industrielle relativement compl\u00e8te. Mais dans le m\u00eame temps, les d\u00e9fauts des batteries lithium-ion ont \u00e9galement attir\u00e9 l'attention.<\/p>\n<p>La raret\u00e9 des ressources est l'une d'entre elles. Les experts ont indiqu\u00e9 que, d'un point de vue mondial, la r\u00e9partition des ressources en lithium est extr\u00eamement in\u00e9gale, avec environ 70% r\u00e9partis en Am\u00e9rique du Sud, et que les ressources en lithium de la Chine ne repr\u00e9sentent que 6% des ressources en lithium du monde.<\/p>\n<p>Comment d\u00e9velopper une technologie de batterie de stockage d'\u00e9nergie \u00e0 faible co\u00fbt qui ne d\u00e9pende pas de ressources rares ? Le rythme de modernisation des nouvelles technologies de stockage de l'\u00e9nergie, repr\u00e9sent\u00e9es par les batteries sodium-ion, s'acc\u00e9l\u00e8re.<\/p>\n<p>Comme les batteries lithium-ion, les batteries sodium-ion sont des batteries secondaires qui d\u00e9pendent des ions sodium pour se d\u00e9placer entre les \u00e9lectrodes positives et n\u00e9gatives afin de compl\u00e9ter la charge et la d\u00e9charge. Li Jianlin, secr\u00e9taire g\u00e9n\u00e9ral du comit\u00e9 des normes de stockage de l'\u00e9nergie de la soci\u00e9t\u00e9 \u00e9lectrotechnique chinoise, a d\u00e9clar\u00e9 que, d'un point de vue mondial, les r\u00e9serves de sodium d\u00e9passent de loin celles du lithium et sont largement distribu\u00e9es. Le co\u00fbt des batteries sodium-ion est inf\u00e9rieur de 30% \u00e0 40% \u00e0 celui des batteries au lithium. En m\u00eame temps, les batteries sodium-ion ont une meilleure s\u00e9curit\u00e9, des performances \u00e0 basse temp\u00e9rature et une dur\u00e9e de vie \u00e9lev\u00e9e, ce qui fait des batteries sodium-ion une voie technique importante pour r\u00e9soudre le probl\u00e8me du \"seul lithium\".<\/p>\n<p><strong>Bonnes perspectives industrielles<\/strong><\/p>\n<p>La Chine attache une grande importance \u00e0 la recherche, au d\u00e9veloppement et \u00e0 l'application des batteries sodium-ion. En 2022, la Chine inclura les batteries sodium-ion dans le \"14e plan quinquennal pour l'innovation scientifique et technologique dans le domaine de l'\u00e9nergie\" afin de soutenir la recherche sur les technologies de pointe et les technologies et \u00e9quipements de base pour les batteries sodium-ion. En janvier 2023, six minist\u00e8res, dont le minist\u00e8re de l'industrie et des technologies de l'information, publient conjointement les \"Guiding Opinions on Promoting the Development of the Energy Electronics Industry\", qui renforcent clairement la recherche technologique sur l'industrialisation des nouvelles batteries de stockage d'\u00e9nergie, la recherche de perc\u00e9es dans les syst\u00e8mes de batteries \u00e0 dur\u00e9e de vie ultra-longue et \u00e0 haute s\u00e9curit\u00e9, les batteries \u00e0 grande \u00e9chelle, \u00e0 grande capacit\u00e9 et \u00e0 haute efficacit\u00e9, le stockage d'\u00e9nergie et d'autres technologies cl\u00e9s, et acc\u00e9l\u00e8rent le d\u00e9veloppement de nouvelles batteries telles que les batteries sodium-ion.<\/p>\n<p>Yu Qingjiao, secr\u00e9taire g\u00e9n\u00e9ral de la Zhongguancun New Battery Technology Innovation Alliance, a d\u00e9clar\u00e9 que 2023 \u00e9tait la \"premi\u00e8re ann\u00e9e de production de masse\" des batteries au sodium dans l'industrie, et que le march\u00e9 chinois des batteries au sodium \u00e9tait en plein essor. \u00c0 l'avenir, les batteries au sodium deviendront un puissant compl\u00e9ment \u00e0 la technologie des batteries au lithium dans de multiples segments tels que les v\u00e9hicules \u00e9lectriques \u00e0 deux et trois roues, le stockage de l'\u00e9nergie domestique, le stockage de l'\u00e9nergie industrielle et commerciale, et les v\u00e9hicules \u00e0 \u00e9nergie nouvelle.<\/p>\n<p>En janvier de cette ann\u00e9e, la marque chinoise de v\u00e9hicules \u00e0 \u00e9nergie nouvelle JAC Yttrium a livr\u00e9 le premier v\u00e9hicule au monde \u00e9quip\u00e9 d'une batterie au sodium. En 2023, les cellules de batterie sodium-ion de premi\u00e8re g\u00e9n\u00e9ration de CATL seront lanc\u00e9es. La cellule de batterie peut \u00eatre charg\u00e9e pendant 15 minutes \u00e0 temp\u00e9rature ambiante, et la puissance peut atteindre plus de 80%. Non seulement le co\u00fbt est plus faible, mais la cha\u00eene industrielle sera \u00e9galement contr\u00f4lable de mani\u00e8re ind\u00e9pendante.<\/p>\n<p>\u00c0 la fin de l'ann\u00e9e derni\u00e8re, l'administration nationale de l'\u00e9nergie a annonc\u00e9 de nouveaux projets pilotes de d\u00e9monstration de stockage d'\u00e9nergie. Parmi les 56 projets pr\u00e9s\u00e9lectionn\u00e9s, il y a deux projets de batteries sodium-ion. Selon Wu Hui, pr\u00e9sident de l'Institut chinois de recherche sur l'industrie des batteries, le processus d'industrialisation des batteries sodium-ion se d\u00e9veloppe rapidement. On estime que d'ici 2030, la demande mondiale de stockage d'\u00e9nergie atteindra environ 1,5 t\u00e9rawattheure (Twh), et les batteries sodium-ion devraient occuper une large place sur le march\u00e9. \"Du stockage de l'\u00e9nergie au niveau du r\u00e9seau au stockage de l'\u00e9nergie industrielle et commerciale, en passant par le stockage de l'\u00e9nergie domestique et le stockage de l'\u00e9nergie portable, l'\u00e9lectricit\u00e9 au sodium sera largement utilis\u00e9e dans tous les produits de stockage de l'\u00e9nergie \u00e0 l'avenir\", a d\u00e9clar\u00e9 Wu Hui.<\/p>\n<p><strong>La route vers l'application est longue<\/strong><\/p>\n<p>Actuellement, les batteries sodium-ion attirent l'attention de plusieurs pays. Le \"Nihon Keizai Shimbun\" a rapport\u00e9 qu'en d\u00e9cembre 2022, le nombre de brevets obtenus par la Chine dans le domaine des batteries sodium-ion repr\u00e9sentait plus de 50% du nombre total de brevets valides dans le monde, le Japon, les \u00c9tats-Unis, la Cor\u00e9e du Sud et la France se classant respectivement de la deuxi\u00e8me \u00e0 la cinqui\u00e8me place. Bit. Sun Jinhua a d\u00e9clar\u00e9 qu'en plus de la nette acc\u00e9l\u00e9ration des perc\u00e9es technologiques et de l'application \u00e0 grande \u00e9chelle des batteries sodium-ion en Chine, de nombreux pays europ\u00e9ens, am\u00e9ricains et asiatiques ont \u00e9galement inclus les batteries sodium-ion dans leurs syst\u00e8mes de d\u00e9veloppement de batteries de stockage d'\u00e9nergie.<\/p>\n<p>Di Kansheng, directeur g\u00e9n\u00e9ral adjoint de Zhejiang Huzhou Guosheng New Energy Technology Co. Ltd, a d\u00e9clar\u00e9 que les batteries sodium-ion peuvent tirer des enseignements de l'histoire du d\u00e9veloppement des batteries au lithium, passer de la production \u00e0 l'industrialisation, r\u00e9duire les co\u00fbts, am\u00e9liorer les performances et promouvoir des sc\u00e9narios d'application dans diverses industries. Dans le m\u00eame temps, il convient d'accorder une priorit\u00e9 absolue \u00e0 la s\u00e9curit\u00e9 et d'utiliser les caract\u00e9ristiques de performance des batteries sodium-ion.<\/p>\n<p>Bien que les perspectives soient prometteuses, les experts estiment que les batteries sodium-ion ont encore un long chemin \u00e0 parcourir avant de pouvoir \u00eatre utilis\u00e9es \u00e0 grande \u00e9chelle.<\/p>\n<p>Yu Qingjiao a d\u00e9clar\u00e9 que le d\u00e9veloppement industriel actuel des batteries au sodium est confront\u00e9 \u00e0 des d\u00e9fis tels qu'une faible densit\u00e9 \u00e9nerg\u00e9tique, une technologie qui doit \u00eatre m\u00fbre, des cha\u00eenes d'approvisionnement qui doivent \u00eatre am\u00e9lior\u00e9es et des niveaux th\u00e9oriques de faible co\u00fbt qui n'ont pas encore \u00e9t\u00e9 atteints. L'ensemble de l'industrie doit se concentrer sur l'innovation collaborative autour des difficult\u00e9s afin de promouvoir l'industrie des piles au sodium vers une isation \u00e9cologique et un d\u00e9veloppement de plus haut niveau.<\/p>","protected":false},"excerpt":{"rendered":"<p>Lithium batteries can be found everywhere in our work and life. From electronic devices such as mobile phones and laptops to new energy  [&#8230;]<\/p>","protected":false},"author":4,"featured_media":23252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-23231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sodium ion batteries open up new energy storage tracks - Delong Energy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.delongtop.com\/fr\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sodium ion batteries open up new energy storage tracks - Delong Energy\" \/>\n<meta property=\"og:description\" content=\"Lithium batteries can be found everywhere in our work and life. From electronic devices such as mobile phones and laptops to new energy [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.delongtop.com\/fr\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/\" \/>\n<meta property=\"og:site_name\" content=\"Delong Energy\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-29T15:58:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-02T06:12:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.delongtop.com\/wp-content\/uploads\/2024\/02\/Sodium-Ion-Battery-vs.-Lithium-Ion-Battery.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Delong\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Delong\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/\",\"url\":\"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/\",\"name\":\"Sodium ion batteries open up new energy storage tracks - Delong Energy\",\"isPartOf\":{\"@id\":\"https:\/\/www.delongtop.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.delongtop.com\/wp-content\/uploads\/2024\/02\/Sodium-Ion-Battery-vs.-Lithium-Ion-Battery.jpg?fit=640%2C594&ssl=1\",\"datePublished\":\"2024-02-29T15:58:26+00:00\",\"dateModified\":\"2024-03-02T06:12:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.delongtop.com\/#\/schema\/person\/a2b36b93a21fe0bafd86071ec13e827d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.delongtop.com\/wp-content\/uploads\/2024\/02\/Sodium-Ion-Battery-vs.-Lithium-Ion-Battery.jpg?fit=640%2C594&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.delongtop.com\/wp-content\/uploads\/2024\/02\/Sodium-Ion-Battery-vs.-Lithium-Ion-Battery.jpg?fit=640%2C594&ssl=1\",\"width\":640,\"height\":594,\"caption\":\"Sodium Ion Battery vs. Lithium Ion Battery\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.delongtop.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sodium ion batteries open up new energy storage tracks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.delongtop.com\/#website\",\"url\":\"https:\/\/www.delongtop.com\/\",\"name\":\"Delong Energy\",\"description\":\"Lithium Ion Battery Manufacturer &amp; Factory In China\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.delongtop.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.delongtop.com\/#\/schema\/person\/a2b36b93a21fe0bafd86071ec13e827d\",\"name\":\"Delong\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.delongtop.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e82b02db42d70c5ff8bcfad9905696cdcdff156ca7fd370090f324379c648677?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e82b02db42d70c5ff8bcfad9905696cdcdff156ca7fd370090f324379c648677?s=96&d=mm&r=g\",\"caption\":\"Delong\"},\"url\":\"https:\/\/www.delongtop.com\/fr\/author\/hzj\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sodium ion batteries open up new energy storage tracks - Delong Energy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.delongtop.com\/fr\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/","og_locale":"fr_FR","og_type":"article","og_title":"Sodium ion batteries open up new energy storage tracks - Delong Energy","og_description":"Lithium batteries can be found everywhere in our work and life. From electronic devices such as mobile phones and laptops to new energy [...]","og_url":"https:\/\/www.delongtop.com\/fr\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/","og_site_name":"Delong Energy","article_published_time":"2024-02-29T15:58:26+00:00","article_modified_time":"2024-03-02T06:12:51+00:00","og_image":[{"width":640,"height":594,"url":"https:\/\/www.delongtop.com\/wp-content\/uploads\/2024\/02\/Sodium-Ion-Battery-vs.-Lithium-Ion-Battery.jpg","type":"image\/jpeg"}],"author":"Delong","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Delong","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/","url":"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/","name":"Sodium ion batteries open up new energy storage tracks - Delong Energy","isPartOf":{"@id":"https:\/\/www.delongtop.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#primaryimage"},"image":{"@id":"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.delongtop.com\/wp-content\/uploads\/2024\/02\/Sodium-Ion-Battery-vs.-Lithium-Ion-Battery.jpg?fit=640%2C594&ssl=1","datePublished":"2024-02-29T15:58:26+00:00","dateModified":"2024-03-02T06:12:51+00:00","author":{"@id":"https:\/\/www.delongtop.com\/#\/schema\/person\/a2b36b93a21fe0bafd86071ec13e827d"},"breadcrumb":{"@id":"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#primaryimage","url":"https:\/\/i0.wp.com\/www.delongtop.com\/wp-content\/uploads\/2024\/02\/Sodium-Ion-Battery-vs.-Lithium-Ion-Battery.jpg?fit=640%2C594&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.delongtop.com\/wp-content\/uploads\/2024\/02\/Sodium-Ion-Battery-vs.-Lithium-Ion-Battery.jpg?fit=640%2C594&ssl=1","width":640,"height":594,"caption":"Sodium Ion Battery vs. Lithium Ion Battery"},{"@type":"BreadcrumbList","@id":"https:\/\/www.delongtop.com\/sodium-ion-batteries-open-up-new-energy-storage-tracks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.delongtop.com\/"},{"@type":"ListItem","position":2,"name":"Sodium ion batteries open up new energy storage tracks"}]},{"@type":"WebSite","@id":"https:\/\/www.delongtop.com\/#website","url":"https:\/\/www.delongtop.com\/","name":"Delong Energy","description":"Lithium Ion Battery Manufacturer &amp; Factory In China","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.delongtop.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.delongtop.com\/#\/schema\/person\/a2b36b93a21fe0bafd86071ec13e827d","name":"Delong","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.delongtop.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e82b02db42d70c5ff8bcfad9905696cdcdff156ca7fd370090f324379c648677?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e82b02db42d70c5ff8bcfad9905696cdcdff156ca7fd370090f324379c648677?s=96&d=mm&r=g","caption":"Delong"},"url":"https:\/\/www.delongtop.com\/fr\/author\/hzj\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.delongtop.com\/wp-content\/uploads\/2024\/02\/Sodium-Ion-Battery-vs.-Lithium-Ion-Battery.jpg?fit=640%2C594&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/posts\/23231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/comments?post=23231"}],"version-history":[{"count":0,"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/posts\/23231\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/media\/23252"}],"wp:attachment":[{"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/media?parent=23231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/categories?post=23231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delongtop.com\/fr\/wp-json\/wp\/v2\/tags?post=23231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}